{"id":1880,"date":"2014-12-20T09:52:17","date_gmt":"2014-12-20T08:52:17","guid":{"rendered":"https:\/\/jakobyrechtsanwaelte.de\/?p=1880"},"modified":"2015-03-05T10:01:26","modified_gmt":"2015-03-05T09:01:26","slug":"vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht","status":"publish","type":"post","link":"https:\/\/jakobyrechtsanwaelte.de\/en\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/","title":{"rendered":"Vortr\u00e4ge zu &#8220;Milieuschutzsatzungen in Berlin&#8221;"},"content":{"rendered":"<p>Im September und Dezember 2014 hat Frau Dr. Herwig hat bei Veranstaltungen des Instituts f\u00fcr St\u00e4dtebau in Berlin\u00a0 Vortr\u00e4ge zum Thema &#8220;Milieuschutzssatzungen in Berlin&#8221; gehalten. Darin hat sie zun\u00e4chst die rechtlichen Grundlagen f\u00fcr soziale Erhaltungsverordnungen, den sogenannten Milieuschutzsatzungen nach \u00a7 172 Abs. 4 BauGB, und die Voraussetzungen f\u00fcr die Festsetzung einer solchen Satzung dargestellt und dann verschiedene Beispiele von Milieuschutzsatzungen in Berlin vorgestellt. <!--more-->Au\u00dferdem hat Frau Dr. Herwig an Fallbeispielen aus der Beratungspraxis erl\u00e4utert, welche Auswirkungen eine Milieuschutzsatzung in der Praxis haben kann. Insbesondere ging es hierbei um die rechtlichen Beschr\u00e4nkungen, die sich in einem Milieuschutzgebiet bei der Umsetzung eines Bauvorhabens f\u00fcr Investoren, Projektentwickler, Bautr\u00e4ger oder Erwerber von Eigentumswohnungen ergeben. Da verschiedene Vertreter der Berliner Bezirke anwesend waren, entstand eine sehr interessante Diskussion zu den st\u00e4dtebaulichen Anforderungen zum Erlass einer Milieuschutzsatzungen.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im September und Dezember 2014 hat Frau Dr. Herwig hat bei Veranstaltungen des Instituts f\u00fcr St\u00e4dtebau in Berlin\u00a0 Vortr\u00e4ge zum Thema &#8220;Milieuschutzssatzungen in Berlin&#8221; gehalten. Darin hat sie zun\u00e4chst die rechtlichen Grundlagen f\u00fcr soziale Erhaltungsverordnungen, den sogenannten Milieuschutzsatzungen nach \u00a7 [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1,3],"tags":[],"class_list":["post-1880","post","type-post","status-publish","format-standard","hentry","category-aktuelles","category-immobilienrecht-baurecht"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vortr\u00e4ge zu &quot;Milieuschutzsatzungen in Berlin&quot;  - Jakoby Rechtsanw\u00e4lte - Berlin<\/title>\n<meta name=\"description\" content=\"Die Kanzlei Jakoby Rechtsanw\u00e4lte in Berlin: Notar und Rechtsanwaltsleistungen im Immobilienrecht, Vergaberecht und Wirtschaftsrecht.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Dr. Lotte Herwig\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vortr\u00e4ge zu \"Milieuschutzsatzungen in Berlin\"  - Jakoby Rechtsanw\u00e4lte - Berlin","description":"Die Kanzlei Jakoby Rechtsanw\u00e4lte in Berlin: Notar und Rechtsanwaltsleistungen im Immobilienrecht, Vergaberecht und Wirtschaftsrecht.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/","twitter_misc":{"Written by":"Dr. Lotte Herwig","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/#article","isPartOf":{"@id":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/"},"author":{"name":"Dr. Lotte Herwig","@id":"https:\/\/jakobyrechtsanwaelte.de\/#\/schema\/person\/05c142fc193a281cd5837edb8d435eda"},"headline":"Vortr\u00e4ge zu &#8220;Milieuschutzsatzungen in Berlin&#8221;","datePublished":"2014-12-20T08:52:17+00:00","dateModified":"2015-03-05T09:01:26+00:00","mainEntityOfPage":{"@id":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/"},"wordCount":146,"articleSection":["Aktuelles","Immobilienrecht-Baurecht"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/","url":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/","name":"Vortr\u00e4ge zu \"Milieuschutzsatzungen in Berlin\" - Jakoby Rechtsanw\u00e4lte - Berlin","isPartOf":{"@id":"https:\/\/jakobyrechtsanwaelte.de\/#website"},"datePublished":"2014-12-20T08:52:17+00:00","dateModified":"2015-03-05T09:01:26+00:00","author":{"@id":"https:\/\/jakobyrechtsanwaelte.de\/#\/schema\/person\/05c142fc193a281cd5837edb8d435eda"},"description":"Die Kanzlei Jakoby Rechtsanw\u00e4lte in Berlin: Notar und Rechtsanwaltsleistungen im Immobilienrecht, Vergaberecht und Wirtschaftsrecht.","breadcrumb":{"@id":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/jakobyrechtsanwaelte.de\/vortrag-zu-milieuschutzsatzungen-berlin-bei-fachtagung-staedtebau-und-recht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/jakobyrechtsanwaelte.de\/en\/"},{"@type":"ListItem","position":2,"name":"Vortr\u00e4ge zu &#8222;Milieuschutzsatzungen in Berlin&#8220;"}]},{"@type":"WebSite","@id":"https:\/\/jakobyrechtsanwaelte.de\/#website","url":"https:\/\/jakobyrechtsanwaelte.de\/","name":"Jakoby Rechtsanw\u00e4lte","description":"Rechtsanw\u00e4lte und Notar","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/jakobyrechtsanwaelte.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/jakobyrechtsanwaelte.de\/#\/schema\/person\/05c142fc193a281cd5837edb8d435eda","name":"Dr. Lotte Herwig","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/9f5f38b6b16460441f99049d026260f05f60f6b9518de3b35c3c6929e41a8afc?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/9f5f38b6b16460441f99049d026260f05f60f6b9518de3b35c3c6929e41a8afc?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9f5f38b6b16460441f99049d026260f05f60f6b9518de3b35c3c6929e41a8afc?s=96&d=mm&r=g","caption":"Dr. Lotte Herwig"},"sameAs":["https:\/\/jakobyrechtsanwaelte.de\/kanzlei\/anwaelte\/dr-lotte-herwig-vormals-dr-lotte-meuth"]}]}},"_links":{"self":[{"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/posts\/1880","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/comments?post=1880"}],"version-history":[{"count":7,"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/posts\/1880\/revisions"}],"predecessor-version":[{"id":1913,"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/posts\/1880\/revisions\/1913"}],"wp:attachment":[{"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/media?parent=1880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/categories?post=1880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/jakobyrechtsanwaelte.de\/en\/wp-json\/wp\/v2\/tags?post=1880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}